{"id":17,"date":"2023-03-15T15:05:30","date_gmt":"2023-03-15T15:05:30","guid":{"rendered":"https:\/\/duplexgroup.co.za\/?page_id=17"},"modified":"2023-03-15T16:52:28","modified_gmt":"2023-03-15T16:52:28","slug":"contact","status":"publish","type":"page","link":"https:\/\/duplexgroup.co.za\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<p>Cliff Cape (Sales \/ Technical support)<br>Mobile : 083 782 9290<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Cliff Cape (Sales \/ Technical support)Mobile : 083 782 9290<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":3,"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":59,"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/pages\/17\/revisions\/59"}],"wp:attachment":[{"href":"https:\/\/duplexgroup.co.za\/index.php\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}